{"id":10135,"date":"2021-06-19T23:27:00","date_gmt":"2021-06-19T21:27:00","guid":{"rendered":"https:\/\/arteeluoghi.it\/?p=10135"},"modified":"2021-06-27T00:18:25","modified_gmt":"2021-06-26T22:18:25","slug":"io-come-me-stesso-collettiva-darte-a-roma","status":"publish","type":"post","link":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/","title":{"rendered":"Io come me stesso. Collettiva d&#8217;arte a Roma"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote\"><p>Si \u00e8 inaugurata il 18 giugno negli spazi dell&#8217;atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito. Venti artisti si sono confrontati sul tema dell&#8217;identit\u00e0<\/p><\/blockquote>\n\n\n\n<p>Io come me stesso, un titolo intrigante per un tema che indaga l&#8217;identit\u00e0. \u00abL\u2019unica persona con cui siamo destinati a trascorrere il resto della nostra vita \u00e8 noi stessi. Pu\u00f2 accadere, pi\u00f9 o meno spesso, che non ci accettiamo, assumendoci le volont\u00e0 di genitori, partner o di ci\u00f2 che ci spinge ad essere la societ\u00e0, decidendo di non \u201cincontrare\u201d quasi mai realmente quella parte pi\u00f9 autentica di noi stessi, conducendoci ad un sentire pi\u00f9 vicino all\u2019immagine di noi che si \u00e8 costruiti\/integrati negli anni, che al vero, intimo, io.\u00bb spiega la curatrice e ideatrice del progetto che ha vestito, dal 18 al 25 giugno, le pareti dell\u2019atelier Pocket Art Studio a Roma  in via della Reginella 11.<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"473\" height=\"1024\" src=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-473x1024.jpg\" alt=\"\" data-id=\"10143\" data-full-url=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-scaled.jpg\" data-link=\"https:\/\/arteeluoghi.it\/?attachment_id=10143\" class=\"wp-image-10143\" srcset=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-473x1024.jpg 473w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-138x300.jpg 138w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-768x1664.jpg 768w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-709x1536.jpg 709w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-945x2048.jpg 945w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137813-scaled.jpg 1182w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"525\" height=\"1024\" src=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-525x1024.jpg\" alt=\"\" data-id=\"10142\" data-full-url=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-scaled.jpg\" data-link=\"https:\/\/arteeluoghi.it\/?attachment_id=10142\" class=\"wp-image-10142\" srcset=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-525x1024.jpg 525w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-154x300.jpg 154w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-768x1498.jpg 768w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-788x1536.jpg 788w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-1050x2048.jpg 1050w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137748-scaled.jpg 1313w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"660\" height=\"1024\" src=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-660x1024.jpg\" alt=\"\" data-id=\"10141\" data-full-url=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-scaled.jpg\" data-link=\"https:\/\/arteeluoghi.it\/?attachment_id=10141\" class=\"wp-image-10141\" srcset=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-660x1024.jpg 660w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-193x300.jpg 193w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-768x1191.jpg 768w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-990x1536.jpg 990w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-1321x2048.jpg 1321w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137627-scaled.jpg 1651w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"473\" height=\"1024\" src=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-473x1024.jpg\" alt=\"\" data-id=\"10139\" data-full-url=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-scaled.jpg\" data-link=\"https:\/\/arteeluoghi.it\/?attachment_id=10139\" class=\"wp-image-10139\" srcset=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-473x1024.jpg 473w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-138x300.jpg 138w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-768x1664.jpg 768w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-709x1536.jpg 709w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-945x2048.jpg 945w, https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137440-scaled.jpg 1182w\" sizes=\"(max-width: 473px) 100vw, 473px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Sono stati selezionati venti artisti, provenienti da diverse cifre stilistiche e diversi luoghi geografici, nelle sezioni pittura, fotografia, illustrazione, installazione e scultura, scegliendo per attinenza al tema, per innovazione e sperimentazione, per l&#8217;originalit\u00e0 e l&#8217;utilizzo dei linguaggi in modo trasversale nonch\u00e9 per il valore della ricerca artistica. Il risultato \u00e8 stato una mostra raffinata e ben curata che ha evidenziato quanto la centralit\u00e0 del tema sia stato particolarmente sentito e apprezzato dagli artisti che si sono confrontati. Hanno esposto le loro opere  Carla Abbondi, Alina, Francesco Burla, Franco Coccopalmeri, Fabio D&#8217;Agostino, Gaia di Leo , Sandro Frinolli P., Sjakar Galajiian, Annalaura Ianni, Marco le Donne, Barbara Lo Faro, Gabriella Lusignani, Rosita Lusignani, Gianni Mora, Eleonora Parenti, Giorgia Ponticello, Giulia Pro, Rosario P. Paolo Saia, Antonella Sorrentino e Mattia Urso.<\/p>\n\n\n\n<p>E per chi non riuscir\u00e0 a vederla, on line il catalogo digitale che consente di visionare le opere selezionate. <br> <\/p>\n\n\n\n<p><a href=\"https:\/\/www.sfogliami.it\/fl\/232072\/pmrkfz5m5xgxffr9znrz4drg9pk4efy8#page\/1\">https:\/\/www.sfogliami.it\/fl\/232072\/pmrkfz5m5xgxffr9znrz4drg9pk4efy8#page\/1<\/a><\/p>\n\n\n\n<p>Dal 18 al 25 giugno 2021, si possono ammirare le opere in esposizione presso l\u2019atelier POCKET ART STUDIO in via della Reginella 11, Roma.<br>Visite nei seguenti giorni: dal luned\u00ec al sabato, orario 11.00\/13.00 &#8211; 16.00\/19.00.<\/p>\n\n\n\n<p><br><br> <br> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 inaugurata il 18 giugno negli spazi dell&#8217;atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito. Venti<\/p>\n","protected":false},"author":1,"featured_media":10138,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[27,3,6],"tags":[3445,3443,3455,3447,3441,3449,3438,3442,3446,3448,3428,3451,3453,3454,3439,3452,3450,3440,3444],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Io come me stesso. Collettiva d&#039;arte a Roma | Arte e Luoghi<\/title>\n<meta name=\"description\" content=\"Si \u00e8 inaugurata il 18 giugno negli spazi dell&#039;atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Io come me stesso. Collettiva d&#039;arte a Roma | Arte e Luoghi\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 inaugurata il 18 giugno negli spazi dell&#039;atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"Arte e Luoghi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArteELuoghi\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-19T21:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-26T22:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@arteeluoghi\" \/>\n<meta name=\"twitter:site\" content=\"@arteeluoghi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/arteeluoghi.it\/#organization\",\"name\":\"Arte e Luoghi\",\"url\":\"https:\/\/arteeluoghi.it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/ArteELuoghi\/\",\"https:\/\/www.instagram.com\/arteeluoghi\/?hl=it\",\"https:\/\/www.youtube.com\/channel\/UCuRVc4JW4-C5sg9rQB-srkw?view_as=subscriber\",\"https:\/\/twitter.com\/arteeluoghi\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg\",\"contentUrl\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg\",\"width\":150,\"height\":150,\"caption\":\"Arte e Luoghi\"},\"image\":{\"@id\":\"https:\/\/arteeluoghi.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arteeluoghi.it\/#website\",\"url\":\"https:\/\/arteeluoghi.it\/\",\"name\":\"Arte e Luoghi\",\"description\":\"Mensile di arte, cultura, turismo e curiosit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/arteeluoghi.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arteeluoghi.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg\",\"contentUrl\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg\",\"width\":2560,\"height\":1474},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage\",\"url\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/\",\"name\":\"Io come me stesso. Collettiva d'arte a Roma | Arte e Luoghi\",\"isPartOf\":{\"@id\":\"https:\/\/arteeluoghi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage\"},\"datePublished\":\"2021-06-19T21:27:00+00:00\",\"dateModified\":\"2021-06-26T22:18:25+00:00\",\"description\":\"Si \u00e8 inaugurata il 18 giugno negli spazi dell'atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito\",\"breadcrumb\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arteeluoghi.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Io come me stesso. Collettiva d&#8217;arte a Roma\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage\"},\"author\":{\"@id\":\"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4\"},\"headline\":\"Io come me stesso. Collettiva d&#8217;arte a Roma\",\"datePublished\":\"2021-06-19T21:27:00+00:00\",\"dateModified\":\"2021-06-26T22:18:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage\"},\"wordCount\":339,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/arteeluoghi.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg\",\"keywords\":[\"Alina\",\"Annalaura Ianni\",\"Antonella Sorrentino e Mattia Urso\",\"Barbara Lo Faro\",\"Carla Abbondi\",\"Eleonora Parenti\",\"Fabio D&#039;Agostino\",\"Francesco Burla\",\"Franco Coccopalmeri\",\"Gabriella Lusignani\",\"Gaia di Leo\",\"Gianni Mora\",\"Giorgia Ponticello\",\"Giulia Pro\",\"Marco le Donne\",\"Rosario P. Paolo Saia\",\"Rosita Lusignani\",\"Sandro Frinolli P.\",\"Sjakar Galajiian\"],\"articleSection\":[\"Arte\",\"Arti visive\",\"Scultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g\",\"caption\":\"Staff\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Io come me stesso. Collettiva d'arte a Roma | Arte e Luoghi","description":"Si \u00e8 inaugurata il 18 giugno negli spazi dell'atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/","og_locale":"it_IT","og_type":"article","og_title":"Io come me stesso. Collettiva d'arte a Roma | Arte e Luoghi","og_description":"Si \u00e8 inaugurata il 18 giugno negli spazi dell'atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito","og_url":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/","og_site_name":"Arte e Luoghi","article_publisher":"https:\/\/www.facebook.com\/ArteELuoghi\/","article_published_time":"2021-06-19T21:27:00+00:00","article_modified_time":"2021-06-26T22:18:25+00:00","og_image":[{"width":2560,"height":1474,"url":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_creator":"@arteeluoghi","twitter_site":"@arteeluoghi","twitter_misc":{"Scritto da":"Staff","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/arteeluoghi.it\/#organization","name":"Arte e Luoghi","url":"https:\/\/arteeluoghi.it\/","sameAs":["https:\/\/www.facebook.com\/ArteELuoghi\/","https:\/\/www.instagram.com\/arteeluoghi\/?hl=it","https:\/\/www.youtube.com\/channel\/UCuRVc4JW4-C5sg9rQB-srkw?view_as=subscriber","https:\/\/twitter.com\/arteeluoghi"],"logo":{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/#logo","inLanguage":"it-IT","url":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg","contentUrl":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg","width":150,"height":150,"caption":"Arte e Luoghi"},"image":{"@id":"https:\/\/arteeluoghi.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/arteeluoghi.it\/#website","url":"https:\/\/arteeluoghi.it\/","name":"Arte e Luoghi","description":"Mensile di arte, cultura, turismo e curiosit\u00e0","publisher":{"@id":"https:\/\/arteeluoghi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arteeluoghi.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg","contentUrl":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg","width":2560,"height":1474},{"@type":"WebPage","@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage","url":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/","name":"Io come me stesso. Collettiva d'arte a Roma | Arte e Luoghi","isPartOf":{"@id":"https:\/\/arteeluoghi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage"},"datePublished":"2021-06-19T21:27:00+00:00","dateModified":"2021-06-26T22:18:25+00:00","description":"Si \u00e8 inaugurata il 18 giugno negli spazi dell'atelier Pocket Art Studio il progetto espositivo ideato da Gina Affinito","breadcrumb":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arteeluoghi.it\/"},{"@type":"ListItem","position":2,"name":"Io come me stesso. Collettiva d&#8217;arte a Roma"}]},{"@type":"Article","@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#article","isPartOf":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage"},"author":{"@id":"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4"},"headline":"Io come me stesso. Collettiva d&#8217;arte a Roma","datePublished":"2021-06-19T21:27:00+00:00","dateModified":"2021-06-26T22:18:25+00:00","mainEntityOfPage":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#webpage"},"wordCount":339,"commentCount":0,"publisher":{"@id":"https:\/\/arteeluoghi.it\/#organization"},"image":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#primaryimage"},"thumbnailUrl":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2021\/06\/1624100137505-scaled.jpg","keywords":["Alina","Annalaura Ianni","Antonella Sorrentino e Mattia Urso","Barbara Lo Faro","Carla Abbondi","Eleonora Parenti","Fabio D&#039;Agostino","Francesco Burla","Franco Coccopalmeri","Gabriella Lusignani","Gaia di Leo","Gianni Mora","Giorgia Ponticello","Giulia Pro","Marco le Donne","Rosario P. Paolo Saia","Rosita Lusignani","Sandro Frinolli P.","Sjakar Galajiian"],"articleSection":["Arte","Arti visive","Scultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arteeluoghi.it\/index.php\/2021\/06\/19\/io-come-me-stesso-collettiva-darte-a-roma\/#respond"]}]},{"@type":"Person","@id":"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4","name":"Staff","image":{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g","caption":"Staff"}}]}},"_links":{"self":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts\/10135"}],"collection":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/comments?post=10135"}],"version-history":[{"count":1,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts\/10135\/revisions"}],"predecessor-version":[{"id":10144,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts\/10135\/revisions\/10144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/media\/10138"}],"wp:attachment":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/media?parent=10135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/categories?post=10135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/tags?post=10135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}