{"id":624,"date":"2012-03-30T15:47:07","date_gmt":"2012-03-30T13:47:07","guid":{"rendered":"http:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/"},"modified":"2012-03-30T15:47:07","modified_gmt":"2012-03-30T13:47:07","slug":"il-quirinale-scrigno-di-tesori","status":"publish","type":"post","link":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/","title":{"rendered":"Il Quirinale, scrigno di tesori"},"content":{"rendered":"<div>\n<h1><span style=\"font-size: x-small;\"><img src=\"\/images\/stories\/logo_mostraquirinale.jpg\" border=\"0\" style=\"float: left; margin: 21px;\" \/><\/span><\/h1>\n<h1><span style=\"font-size: x-small;\">Roma, Palazzo del Quirinale. La mostra \u00e8 prorogata fino al 1\u00b0 aprile 2012<\/span><\/h1>\n<h1>Il Quirinale. Dall\u2019Unit\u00e0 d&#8217;Italia ai nostri giorni<\/h1>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<p>La \u201cCasa degli Italiani\u201d si racconta con un contributo specifico della  Presidenza della Repubblica alle celebrazioni del 150\u00b0 anniversario  dell\u2019Unit\u00e0 d\u2019Italia: dal 26 novembre 2011 al 17 marzo 2012 (con proroga  al 1\u00b0 aprile 2012) il Palazzo del Quirinale \u2013 tra il Cortile d\u2019Onore e  le sale del Piano Nobile \u2013 ospita la mostra \u201cIl Quirinale. Dall\u2019Unit\u00e0  d&#8217;Italia ai nostri giorni\u201d.<\/p>\n<p> Promossa dal Segretariato Generale della Presidenza della Repubblica  Italiana e organizzata in collaborazione con l\u2019Associazione Civita, la  mostra \u00e8 curata da Paola Carucci e Louis Godart con l\u2019allestimento del  maestro Luca Ronconi. <br \/> Il 150\u00b0 anniversario dell\u2019Unificazione nazionale ha costituito  l\u2019occasione per un approfondimento storiografico e una riflessione sulle  vicende storico-politiche e istituzionali che hanno segnato  l\u2019evoluzione dello Stato italiano.<\/p>\n<p> Il Palazzo del Quirinale costituisce l\u2019espressione simbolica di un  percorso complesso, che ha posto l\u2019Unit\u00e0 nazionale di fronte a prove  durissime e a momenti di grave crisi, ma anche a significativi momenti  di consolidamento dello Stato: edificato dai papi nel 1583, \u00e8 diventato  nel 1870 residenza dei sovrani d\u2019Italia e dal 1946 \u00e8 sede della  Presidenza della Repubblica. <br \/> Il filo conduttore della mostra \u00e8 costituito dalla funzione di  rappresentanza dell\u2019Unit\u00e0 nazionale che lo Statuto Albertino prima e  soprattutto la Costituzione poi hanno conferito al Capo dello Stato, e  dal modo in cui tale funzione \u00e8 stata interpretata e attuata dalle  diverse personalit\u00e0 che hanno ricoperto la pi\u00f9 alta carica istituzionale  della nazione.<\/p>\n<p>  <!--more-->  La mostra intende, da una parte, illustrare il patrimonio artistico, la  politica di costante acquisizione di opere d\u2019arte da parte dei sovrani  di casa Savoia, e il successivo impegno dei Presidenti della Repubblica  volto allo studio, al restauro, alla scoperta, alla gestione degli  edifici, dei giardini e dei tesori d\u2019arte custoditi nel Palazzo.  Dall\u2019altra, sotto il profilo storico-istituzionale, la riflessione parte  dal ruolo svolto dai Savoia (e dalle consorti dei sovrani, in  particolare dalla regina Margherita alla quale \u00e8 dedicata un\u2019apposita  sezione relativa alla sua Biblioteca conservata presso il Quirinale) per  poi approfondire l\u2019attivit\u00e0 dei Presidenti della Repubblica.<\/p>\n<p>Verranno, dunque, presentati oggetti del Quirinale \u2013 libri, quadri,  livree \u2013, documenti di archivio e ritagli stampa, con ampio uso di  fotografie, registrazioni sonore e riprese cinematografiche e  televisive. <br \/> La mostra dar\u00e0 ampio spazio al ruolo di \u201crappresentanza dell\u2019Unit\u00e0  nazionale\u201d, scolpito nell\u2019articolo 87 della Costituzione, assolta sul  piano internazionale dalle visite all\u2019estero e dagli incontri con i Capi  di Stato esteri; mentre il rapporto con la societ\u00e0 emerger\u00e0 anche dai  viaggi in Italia, dalle udienze e dalle cerimonie presso il Quirinale. <br \/>La  mostra, pensata per un pubblico ampio e rivolta in particolare ai  giovani e al mondo della scuola, si avvale non solo delle fonti  documentali conservate presso il Palazzo del Quirinale, ma anche di  materiale iconografico e documenti provenienti dall\u2019Archivio Centrale  dello Stato, l\u2019Istituto Luce, le Teche Rai e altri archivi, musei e  istituzioni.<\/p>\n<\/p><\/div>\n<h1><span style=\"font-size: x-small;\"> <\/p>\n<hr \/>\n<p> Roma, Palazzo del Quirinale<\/span><\/h1>\n<div>30 Novembre 2011            &#8211; 1 Aprile 2012<\/div>\n<div><strong>Indirizzo<\/strong>: Piazza del Quirinale<\/div>\n<div><strong>Orario<\/strong>: Dal marted\u00ec al sabato dalle 10.00 alle 13.00 e dalle 15.30 alle 18.30. Domenica: dalle 8.30 alle 12.00. La mostra rimane chiusa tutti i luned\u00ec e il giorno 20 marzo 2012<\/div>\n<div><strong>Biglietto<\/strong>: Ingresso gratuito<\/div>\n<div>(fonte: comunicato stampa)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Roma, Palazzo del Quirinale. La mostra \u00e8 prorogata fino al 1\u00b0 aprile 2012 Il Quirinale. Dall\u2019Unit\u00e0 d&#8217;Italia ai nostri giorni<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Quirinale, scrigno di tesori | Arte e Luoghi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Quirinale, scrigno di tesori | Arte e Luoghi\" \/>\n<meta property=\"og:description\" content=\"Roma, Palazzo del Quirinale. La mostra \u00e8 prorogata fino al 1\u00b0 aprile 2012 Il Quirinale. Dall\u2019Unit\u00e0 d&#8217;Italia ai nostri giorni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/\" \/>\n<meta property=\"og:site_name\" content=\"Arte e Luoghi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArteELuoghi\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-30T13:47:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arteeluoghi.it\/images\/stories\/logo_mostraquirinale.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@arteeluoghi\" \/>\n<meta name=\"twitter:site\" content=\"@arteeluoghi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/arteeluoghi.it\/#organization\",\"name\":\"Arte e Luoghi\",\"url\":\"https:\/\/arteeluoghi.it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/ArteELuoghi\/\",\"https:\/\/www.instagram.com\/arteeluoghi\/?hl=it\",\"https:\/\/www.youtube.com\/channel\/UCuRVc4JW4-C5sg9rQB-srkw?view_as=subscriber\",\"https:\/\/twitter.com\/arteeluoghi\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg\",\"contentUrl\":\"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg\",\"width\":150,\"height\":150,\"caption\":\"Arte e Luoghi\"},\"image\":{\"@id\":\"https:\/\/arteeluoghi.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arteeluoghi.it\/#website\",\"url\":\"https:\/\/arteeluoghi.it\/\",\"name\":\"Arte e Luoghi\",\"description\":\"Mensile di arte, cultura, turismo e curiosit\u00e0\",\"publisher\":{\"@id\":\"https:\/\/arteeluoghi.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arteeluoghi.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"\/images\/stories\/logo_mostraquirinale.jpg\",\"contentUrl\":\"\/images\/stories\/logo_mostraquirinale.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage\",\"url\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/\",\"name\":\"Il Quirinale, scrigno di tesori | Arte e Luoghi\",\"isPartOf\":{\"@id\":\"https:\/\/arteeluoghi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage\"},\"datePublished\":\"2012-03-30T13:47:07+00:00\",\"dateModified\":\"2012-03-30T13:47:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arteeluoghi.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Quirinale, scrigno di tesori\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage\"},\"author\":{\"@id\":\"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4\"},\"headline\":\"Il Quirinale, scrigno di tesori\",\"datePublished\":\"2012-03-30T13:47:07+00:00\",\"dateModified\":\"2012-03-30T13:47:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/arteeluoghi.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage\"},\"thumbnailUrl\":\"\/images\/stories\/logo_mostraquirinale.jpg\",\"articleSection\":[\"Arti visive\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/arteeluoghi.it\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g\",\"caption\":\"Staff\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Quirinale, scrigno di tesori | Arte e Luoghi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/","og_locale":"it_IT","og_type":"article","og_title":"Il Quirinale, scrigno di tesori | Arte e Luoghi","og_description":"Roma, Palazzo del Quirinale. La mostra \u00e8 prorogata fino al 1\u00b0 aprile 2012 Il Quirinale. Dall\u2019Unit\u00e0 d&#8217;Italia ai nostri giorni","og_url":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/","og_site_name":"Arte e Luoghi","article_publisher":"https:\/\/www.facebook.com\/ArteELuoghi\/","article_published_time":"2012-03-30T13:47:07+00:00","og_image":[{"url":"https:\/\/arteeluoghi.it\/images\/stories\/logo_mostraquirinale.jpg"}],"twitter_card":"summary","twitter_creator":"@arteeluoghi","twitter_site":"@arteeluoghi","twitter_misc":{"Scritto da":"Staff","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/arteeluoghi.it\/#organization","name":"Arte e Luoghi","url":"https:\/\/arteeluoghi.it\/","sameAs":["https:\/\/www.facebook.com\/ArteELuoghi\/","https:\/\/www.instagram.com\/arteeluoghi\/?hl=it","https:\/\/www.youtube.com\/channel\/UCuRVc4JW4-C5sg9rQB-srkw?view_as=subscriber","https:\/\/twitter.com\/arteeluoghi"],"logo":{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/#logo","inLanguage":"it-IT","url":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg","contentUrl":"https:\/\/arteeluoghi.it\/wp-content\/uploads\/2018\/08\/logoinstagramarte.jpg","width":150,"height":150,"caption":"Arte e Luoghi"},"image":{"@id":"https:\/\/arteeluoghi.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/arteeluoghi.it\/#website","url":"https:\/\/arteeluoghi.it\/","name":"Arte e Luoghi","description":"Mensile di arte, cultura, turismo e curiosit\u00e0","publisher":{"@id":"https:\/\/arteeluoghi.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arteeluoghi.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage","inLanguage":"it-IT","url":"\/images\/stories\/logo_mostraquirinale.jpg","contentUrl":"\/images\/stories\/logo_mostraquirinale.jpg"},{"@type":"WebPage","@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage","url":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/","name":"Il Quirinale, scrigno di tesori | Arte e Luoghi","isPartOf":{"@id":"https:\/\/arteeluoghi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage"},"datePublished":"2012-03-30T13:47:07+00:00","dateModified":"2012-03-30T13:47:07+00:00","breadcrumb":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arteeluoghi.it\/"},{"@type":"ListItem","position":2,"name":"Il Quirinale, scrigno di tesori"}]},{"@type":"Article","@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#article","isPartOf":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage"},"author":{"@id":"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4"},"headline":"Il Quirinale, scrigno di tesori","datePublished":"2012-03-30T13:47:07+00:00","dateModified":"2012-03-30T13:47:07+00:00","mainEntityOfPage":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#webpage"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/arteeluoghi.it\/#organization"},"image":{"@id":"https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#primaryimage"},"thumbnailUrl":"\/images\/stories\/logo_mostraquirinale.jpg","articleSection":["Arti visive"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arteeluoghi.it\/index.php\/2012\/03\/30\/il-quirinale-scrigno-di-tesori\/#respond"]}]},{"@type":"Person","@id":"https:\/\/arteeluoghi.it\/#\/schema\/person\/f84e814e36e91e01448ee07eaadd41d4","name":"Staff","image":{"@type":"ImageObject","@id":"https:\/\/arteeluoghi.it\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/49d2f9e46271bb04e19cebfaf141313a?s=96&d=blank&r=g","caption":"Staff"}}]}},"_links":{"self":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts\/624"}],"collection":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/comments?post=624"}],"version-history":[{"count":0,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/posts\/624\/revisions"}],"wp:attachment":[{"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/media?parent=624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/categories?post=624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arteeluoghi.it\/index.php\/wp-json\/wp\/v2\/tags?post=624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}